{"id":68,"date":"2013-09-18T00:00:00","date_gmt":"2013-09-18T00:00:00","guid":{"rendered":"https:\/\/blog.wtransnet.com\/fr\/wconnecta-madrid-accueille-en-octobre-les-entreprises-les-plus-importantes-du-secteur-pour-ledition-la-plus-internationale\/"},"modified":"2016-02-09T11:13:05","modified_gmt":"2016-02-09T11:13:05","slug":"wconnecta-madrid-accueille-en-octobre-les-entreprises-les-plus-importantes-du-secteur-pour-ledition-la-plus-internationale","status":"publish","type":"post","link":"https:\/\/blog.wtransnet.com\/fr\/wconnecta-madrid-accueille-en-octobre-les-entreprises-les-plus-importantes-du-secteur-pour-ledition-la-plus-internationale\/","title":{"rendered":"WConnecta Madrid accueille en octobre les entreprises les plus importantes du secteur pour l\u2019\u00e9dition la plus internationale"},"content":{"rendered":"<p class=\"rtejustify\">La IV\u00e8me rencontre Intern<a href=\"https:\/\/blog.wtransnet.com\/fr\/wp-content\/uploads\/sites\/4\/1313\/09\/graficos-fr.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-884\" src=\"https:\/\/blog.wtransnet.com\/fr\/wp-content\/uploads\/sites\/4\/1313\/09\/graficos-fr.jpg\" alt=\"graficos-fr\" width=\"220\" height=\"468\" \/><\/a>ationale des Professionnels du Transport et de la Logistique qui aura lieu le 18 octobre 2013 \u00e0 Madrid, se consolide comme un des \u00e9v\u00e9nements les plus importants du secteur, et fait un pas en avant quant \u00e0 son \u00e9volution et r\u00e9percutions.<\/p>\n<p class=\"rtejustify\">Ne restant \u00e0 peine un mois avant que les entreprises les plus importantes du secteur se donnent rendez-vous au WConnecta Madrid 2013, nous pouvons avancer des donn\u00e9es sur la participation. D\u2019une part, les pays \u00e9tant les plus repr\u00e9sent\u00e9s: Espagne, Allemagne, France, Pologne et Italie;\u00a0d\u2019autre part, les sp\u00e9cialit\u00e9s de camion les plus propos\u00e9s: tautliners, frigorifiques et marchandises sp\u00e9cifiques. L\u2019int\u00e9r\u00eat augmente \u00e9galement pour les lignes de transport depuis ou pour l\u2019Allemagne, la P\u00e9ninsule Ib\u00e9rique, la France, le Benelux et l\u2019Europe de l\u2019Ouest.<\/p>\n<p class=\"rtejustify\"><strong>64% des entreprises inscrites proposent fret et v\u00e9hicules \u00a0<\/strong><\/p>\n<p class=\"rtejustify\">La nouveaut\u00e9 la plus remarquable de cette \u00e9dition \u00e9tant l\u2019incorporation d\u2019un NETWORKING CARGO AREA, un espace d\u00e9di\u00e9 exclusivement \u00e0 des entretiens priv\u00e9s avec des entreprises de logistique et commissionnaires de transport. Il est donc int\u00e9ressant de souligner que 64% des entreprises inscrites viennent sp\u00e9cialement au WConnecta \u00e0 la recherche de nouveaux fournisseurs.<\/p>\n<p class=\"rtejustify\">En vue d\u2019accro\u00eetre les relations entre entrepreneurs et professionnels du secteur en Europe, WConnecta devient l\u2019opportunit\u00e9 pour conna\u00eetre, prendre contact et \u00e9tablir des collaborations avec des soci\u00e9t\u00e9s europ\u00e9ennes.<\/p>\n<p class=\"rtejustify\">Les inscriptions au WConnecta Madrid 2013\u00a0 sont ouvertes jusqu\u2019au 5 Octobre bien que les agendas d\u2019entretiens priv\u00e9s se remplissent rapidement, c\u2019est pourquoi il est important de garantir votre place et organiser votre journ\u00e9e au WConnecta le plus t\u00f4t possible.<\/p>\n<div>\n<div>\n<div>\n<p class=\"rtejustify\">+ info:\u00a0<a href=\"http:\/\/www.wconnecta.com\/es\/index.html\" target=\"_blank\">WConnecta<\/a><\/p>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>La IV\u00e8me rencontre Internationale des Professionnels du Transport et de la Logistique qui aura lieu le 18 octobre 2013 \u00e0 Madrid, se consolide comme un des \u00e9v\u00e9nements les plus importants du secteur, et fait un pas en avant quant \u00e0 son \u00e9volution et r\u00e9percutions. Ne restant \u00e0 peine un mois avant que les entreprises les &hellip;<\/p>\n","protected":false},"author":6,"featured_media":883,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[5,166],"tags":[18,24,19,10],"class_list":["post-68","post","type-post","status-publish","format-standard","has-post-thumbnail","","category-actes-evenements","category-blog","tag-madrid-2013","tag-speed-networking","tag-wconnecta","tag-wtransnet"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>WConnecta Madrid accueille en octobre les entreprises les plus importantes du secteur pour l\u2019\u00e9dition la plus internationale - Blog Wtransnet France<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blog.wtransnet.com\/fr\/wconnecta-madrid-accueille-en-octobre-les-entreprises-les-plus-importantes-du-secteur-pour-ledition-la-plus-internationale\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"WConnecta Madrid accueille en octobre les entreprises les plus importantes du secteur pour l\u2019\u00e9dition la plus internationale - Blog Wtransnet France\" \/>\n<meta property=\"og:description\" content=\"La IV\u00e8me rencontre Internationale des Professionnels du Transport et de la Logistique qui aura lieu le 18 octobre 2013 \u00e0 Madrid, se consolide comme un des \u00e9v\u00e9nements les plus importants du secteur, et fait un pas en avant quant \u00e0 son \u00e9volution et r\u00e9percutions. Ne restant \u00e0 peine un mois avant que les entreprises les &hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blog.wtransnet.com\/fr\/wconnecta-madrid-accueille-en-octobre-les-entreprises-les-plus-importantes-du-secteur-pour-ledition-la-plus-internationale\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog Wtransnet France\" \/>\n<meta property=\"article:published_time\" content=\"2013-09-18T00:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-02-09T11:13:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/blog.wtransnet.com\/fr\/wp-content\/uploads\/sites\/4\/1313\/09\/150x150.gif\" \/>\n\t<meta property=\"og:image:width\" content=\"150\" \/>\n\t<meta property=\"og:image:height\" content=\"150\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/gif\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/blog.wtransnet.com\/fr\/wconnecta-madrid-accueille-en-octobre-les-entreprises-les-plus-importantes-du-secteur-pour-ledition-la-plus-internationale\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/blog.wtransnet.com\/fr\/wconnecta-madrid-accueille-en-octobre-les-entreprises-les-plus-importantes-du-secteur-pour-ledition-la-plus-internationale\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"WConnecta Madrid accueille en octobre les entreprises les plus importantes du secteur pour l\u2019\u00e9dition la plus internationale\",\"datePublished\":\"2013-09-18T00:00:00+00:00\",\"dateModified\":\"2016-02-09T11:13:05+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/blog.wtransnet.com\/fr\/wconnecta-madrid-accueille-en-octobre-les-entreprises-les-plus-importantes-du-secteur-pour-ledition-la-plus-internationale\/\"},\"wordCount\":301,\"commentCount\":0,\"image\":{\"@id\":\"https:\/\/blog.wtransnet.com\/fr\/wconnecta-madrid-accueille-en-octobre-les-entreprises-les-plus-importantes-du-secteur-pour-ledition-la-plus-internationale\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/blog.wtransnet.com\/fr\/wp-content\/uploads\/sites\/4\/1313\/09\/150x150.gif\",\"keywords\":[\"madrid 2013\",\"speed networking\",\"wconnecta\",\"wtransnet\"],\"articleSection\":[\"Actes et Ev\u00e8nements\",\"Blog\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/blog.wtransnet.com\/fr\/wconnecta-madrid-accueille-en-octobre-les-entreprises-les-plus-importantes-du-secteur-pour-ledition-la-plus-internationale\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/blog.wtransnet.com\/fr\/wconnecta-madrid-accueille-en-octobre-les-entreprises-les-plus-importantes-du-secteur-pour-ledition-la-plus-internationale\/\",\"url\":\"https:\/\/blog.wtransnet.com\/fr\/wconnecta-madrid-accueille-en-octobre-les-entreprises-les-plus-importantes-du-secteur-pour-ledition-la-plus-internationale\/\",\"name\":\"WConnecta Madrid accueille en octobre les entreprises les plus importantes du secteur pour l\u2019\u00e9dition la plus internationale - Blog Wtransnet France\",\"isPartOf\":{\"@id\":\"https:\/\/blog.wtransnet.com\/fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/blog.wtransnet.com\/fr\/wconnecta-madrid-accueille-en-octobre-les-entreprises-les-plus-importantes-du-secteur-pour-ledition-la-plus-internationale\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/blog.wtransnet.com\/fr\/wconnecta-madrid-accueille-en-octobre-les-entreprises-les-plus-importantes-du-secteur-pour-ledition-la-plus-internationale\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/blog.wtransnet.com\/fr\/wp-content\/uploads\/sites\/4\/1313\/09\/150x150.gif\",\"datePublished\":\"2013-09-18T00:00:00+00:00\",\"dateModified\":\"2016-02-09T11:13:05+00:00\",\"author\":{\"@id\":\"\"},\"breadcrumb\":{\"@id\":\"https:\/\/blog.wtransnet.com\/fr\/wconnecta-madrid-accueille-en-octobre-les-entreprises-les-plus-importantes-du-secteur-pour-ledition-la-plus-internationale\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/blog.wtransnet.com\/fr\/wconnecta-madrid-accueille-en-octobre-les-entreprises-les-plus-importantes-du-secteur-pour-ledition-la-plus-internationale\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/blog.wtransnet.com\/fr\/wconnecta-madrid-accueille-en-octobre-les-entreprises-les-plus-importantes-du-secteur-pour-ledition-la-plus-internationale\/#primaryimage\",\"url\":\"https:\/\/blog.wtransnet.com\/fr\/wp-content\/uploads\/sites\/4\/1313\/09\/150x150.gif\",\"contentUrl\":\"https:\/\/blog.wtransnet.com\/fr\/wp-content\/uploads\/sites\/4\/1313\/09\/150x150.gif\",\"width\":150,\"height\":150},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/blog.wtransnet.com\/fr\/wconnecta-madrid-accueille-en-octobre-les-entreprises-les-plus-importantes-du-secteur-pour-ledition-la-plus-internationale\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/blog.wtransnet.com\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"WConnecta Madrid accueille en octobre les entreprises les plus importantes du secteur pour l\u2019\u00e9dition la plus internationale\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/blog.wtransnet.com\/fr\/#website\",\"url\":\"https:\/\/blog.wtransnet.com\/fr\/\",\"name\":\"Blog Wtransnet France\",\"description\":\"Blog Wtransnet France: Actualit\u00e9s transport et logistique\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/blog.wtransnet.com\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"\",\"url\":\"https:\/\/blog.wtransnet.com\/fr\/author\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"WConnecta Madrid accueille en octobre les entreprises les plus importantes du secteur pour l\u2019\u00e9dition la plus internationale - Blog Wtransnet France","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blog.wtransnet.com\/fr\/wconnecta-madrid-accueille-en-octobre-les-entreprises-les-plus-importantes-du-secteur-pour-ledition-la-plus-internationale\/","og_locale":"es_ES","og_type":"article","og_title":"WConnecta Madrid accueille en octobre les entreprises les plus importantes du secteur pour l\u2019\u00e9dition la plus internationale - Blog Wtransnet France","og_description":"La IV\u00e8me rencontre Internationale des Professionnels du Transport et de la Logistique qui aura lieu le 18 octobre 2013 \u00e0 Madrid, se consolide comme un des \u00e9v\u00e9nements les plus importants du secteur, et fait un pas en avant quant \u00e0 son \u00e9volution et r\u00e9percutions. Ne restant \u00e0 peine un mois avant que les entreprises les &hellip;","og_url":"https:\/\/blog.wtransnet.com\/fr\/wconnecta-madrid-accueille-en-octobre-les-entreprises-les-plus-importantes-du-secteur-pour-ledition-la-plus-internationale\/","og_site_name":"Blog Wtransnet France","article_published_time":"2013-09-18T00:00:00+00:00","article_modified_time":"2016-02-09T11:13:05+00:00","og_image":[{"width":150,"height":150,"url":"https:\/\/blog.wtransnet.com\/fr\/wp-content\/uploads\/sites\/4\/1313\/09\/150x150.gif","type":"image\/gif"}],"twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/blog.wtransnet.com\/fr\/wconnecta-madrid-accueille-en-octobre-les-entreprises-les-plus-importantes-du-secteur-pour-ledition-la-plus-internationale\/#article","isPartOf":{"@id":"https:\/\/blog.wtransnet.com\/fr\/wconnecta-madrid-accueille-en-octobre-les-entreprises-les-plus-importantes-du-secteur-pour-ledition-la-plus-internationale\/"},"author":{"name":"","@id":""},"headline":"WConnecta Madrid accueille en octobre les entreprises les plus importantes du secteur pour l\u2019\u00e9dition la plus internationale","datePublished":"2013-09-18T00:00:00+00:00","dateModified":"2016-02-09T11:13:05+00:00","mainEntityOfPage":{"@id":"https:\/\/blog.wtransnet.com\/fr\/wconnecta-madrid-accueille-en-octobre-les-entreprises-les-plus-importantes-du-secteur-pour-ledition-la-plus-internationale\/"},"wordCount":301,"commentCount":0,"image":{"@id":"https:\/\/blog.wtransnet.com\/fr\/wconnecta-madrid-accueille-en-octobre-les-entreprises-les-plus-importantes-du-secteur-pour-ledition-la-plus-internationale\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.wtransnet.com\/fr\/wp-content\/uploads\/sites\/4\/1313\/09\/150x150.gif","keywords":["madrid 2013","speed networking","wconnecta","wtransnet"],"articleSection":["Actes et Ev\u00e8nements","Blog"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/blog.wtransnet.com\/fr\/wconnecta-madrid-accueille-en-octobre-les-entreprises-les-plus-importantes-du-secteur-pour-ledition-la-plus-internationale\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/blog.wtransnet.com\/fr\/wconnecta-madrid-accueille-en-octobre-les-entreprises-les-plus-importantes-du-secteur-pour-ledition-la-plus-internationale\/","url":"https:\/\/blog.wtransnet.com\/fr\/wconnecta-madrid-accueille-en-octobre-les-entreprises-les-plus-importantes-du-secteur-pour-ledition-la-plus-internationale\/","name":"WConnecta Madrid accueille en octobre les entreprises les plus importantes du secteur pour l\u2019\u00e9dition la plus internationale - Blog Wtransnet France","isPartOf":{"@id":"https:\/\/blog.wtransnet.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/blog.wtransnet.com\/fr\/wconnecta-madrid-accueille-en-octobre-les-entreprises-les-plus-importantes-du-secteur-pour-ledition-la-plus-internationale\/#primaryimage"},"image":{"@id":"https:\/\/blog.wtransnet.com\/fr\/wconnecta-madrid-accueille-en-octobre-les-entreprises-les-plus-importantes-du-secteur-pour-ledition-la-plus-internationale\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.wtransnet.com\/fr\/wp-content\/uploads\/sites\/4\/1313\/09\/150x150.gif","datePublished":"2013-09-18T00:00:00+00:00","dateModified":"2016-02-09T11:13:05+00:00","author":{"@id":""},"breadcrumb":{"@id":"https:\/\/blog.wtransnet.com\/fr\/wconnecta-madrid-accueille-en-octobre-les-entreprises-les-plus-importantes-du-secteur-pour-ledition-la-plus-internationale\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blog.wtransnet.com\/fr\/wconnecta-madrid-accueille-en-octobre-les-entreprises-les-plus-importantes-du-secteur-pour-ledition-la-plus-internationale\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/blog.wtransnet.com\/fr\/wconnecta-madrid-accueille-en-octobre-les-entreprises-les-plus-importantes-du-secteur-pour-ledition-la-plus-internationale\/#primaryimage","url":"https:\/\/blog.wtransnet.com\/fr\/wp-content\/uploads\/sites\/4\/1313\/09\/150x150.gif","contentUrl":"https:\/\/blog.wtransnet.com\/fr\/wp-content\/uploads\/sites\/4\/1313\/09\/150x150.gif","width":150,"height":150},{"@type":"BreadcrumbList","@id":"https:\/\/blog.wtransnet.com\/fr\/wconnecta-madrid-accueille-en-octobre-les-entreprises-les-plus-importantes-du-secteur-pour-ledition-la-plus-internationale\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/blog.wtransnet.com\/fr\/"},{"@type":"ListItem","position":2,"name":"WConnecta Madrid accueille en octobre les entreprises les plus importantes du secteur pour l\u2019\u00e9dition la plus internationale"}]},{"@type":"WebSite","@id":"https:\/\/blog.wtransnet.com\/fr\/#website","url":"https:\/\/blog.wtransnet.com\/fr\/","name":"Blog Wtransnet France","description":"Blog Wtransnet France: Actualit\u00e9s transport et logistique","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blog.wtransnet.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"","url":"https:\/\/blog.wtransnet.com\/fr\/author\/"}]}},"_links":{"self":[{"href":"https:\/\/blog.wtransnet.com\/fr\/wp-json\/wp\/v2\/posts\/68","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.wtransnet.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.wtransnet.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.wtransnet.com\/fr\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.wtransnet.com\/fr\/wp-json\/wp\/v2\/comments?post=68"}],"version-history":[{"count":0,"href":"https:\/\/blog.wtransnet.com\/fr\/wp-json\/wp\/v2\/posts\/68\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blog.wtransnet.com\/fr\/wp-json\/wp\/v2\/media\/883"}],"wp:attachment":[{"href":"https:\/\/blog.wtransnet.com\/fr\/wp-json\/wp\/v2\/media?parent=68"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.wtransnet.com\/fr\/wp-json\/wp\/v2\/categories?post=68"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.wtransnet.com\/fr\/wp-json\/wp\/v2\/tags?post=68"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}