{"id":12,"date":"2012-03-20T00:00:00","date_gmt":"2012-03-20T00:00:00","guid":{"rendered":"https:\/\/blog.wtransnet.com\/pt\/2012\/03\/20\/2-976-entrevistas-inter-profissionais-na-ii-edicao-de-madrid-connecta\/"},"modified":"2016-02-03T16:57:40","modified_gmt":"2016-02-03T16:57:40","slug":"2-976-entrevistas-inter-profissionais-na-ii-edicao-de-madrid-connecta","status":"publish","type":"post","link":"https:\/\/blog.wtransnet.com\/pt\/2-976-entrevistas-inter-profissionais-na-ii-edicao-de-madrid-connecta\/","title":{"rendered":"2.976 Entrevistas inter-profissionais na II Edi\u00e7\u00e3o de Madrid Connecta"},"content":{"rendered":"<h3 class=\"rtejustify\"><b>214 profissionais e 10 pa\u00edses europeus representados na maior jornada de Networking do sector<\/b><\/h3>\n<p class=\"rtejustify\">214 profissionais reuniram-se no passado 18 de Novembro em Madrid no II Encontro Internacional de Profissionais do Transporte de da Log\u00edstica organizado pela Funda\u00e7\u00e3o Wtransnet.<\/p>\n<p class=\"rtejustify\">O Objectivo: ajudar as empresas do sector a encontrar novos colaboradores de confian\u00e7a para gerar novas oportunidades de neg\u00f3cio, atrav\u00e9s de sess\u00f5es de <i>speed networking<\/i> e entrevistas pessoais marcadas previamente de acordo com os interesses dos pr\u00f3prios assistentes e das especialidades das suas empresas.<\/p>\n<p class=\"rtejustify\">A empatia e a participa\u00e7\u00e3o activa foram as notas dominantes nas 2.976 entrevistas que tiveram lugar em apenas uma jornada de trabalho.<\/p>\n<p class=\"rtejustify\">A impress\u00e3o generalizada entre os assistentes ap\u00f3s finalizar o encontro era de \u00abter feito um bom trabalho\u00bb.<\/p>\n<p class=\"rtejustify\">O Comit\u00e9 Organizador de Madrid Connecta j\u00e1 trabalha numa nova edi\u00e7\u00e3o, que provavelmente se celebre no pr\u00f3ximo Outono.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>214 profissionais e 10 pa\u00edses europeus representados na maior jornada de Networking do sector 214 profissionais reuniram-se no passado 18 de Novembro em Madrid no II Encontro Internacional de Profissionais do Transporte de da Log\u00edstica organizado pela Funda\u00e7\u00e3o Wtransnet. O Objectivo: ajudar as empresas do sector a encontrar novos colaboradores de confian\u00e7a para gerar novas &hellip;<\/p>\n","protected":false},"author":1,"featured_media":146,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[5,180],"tags":[],"class_list":["post-12","post","type-post","status-publish","format-standard","has-post-thumbnail","","category-fundacao-wtransnet","category-transporte-atualidade"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>2.976 Entrevistas inter-profissionais na II Edi\u00e7\u00e3o de Madrid Connecta - Blog Wtransnet Portugal<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blog.wtransnet.com\/pt\/2-976-entrevistas-inter-profissionais-na-ii-edicao-de-madrid-connecta\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"2.976 Entrevistas inter-profissionais na II Edi\u00e7\u00e3o de Madrid Connecta - Blog Wtransnet Portugal\" \/>\n<meta property=\"og:description\" content=\"214 profissionais e 10 pa\u00edses europeus representados na maior jornada de Networking do sector 214 profissionais reuniram-se no passado 18 de Novembro em Madrid no II Encontro Internacional de Profissionais do Transporte de da Log\u00edstica organizado pela Funda\u00e7\u00e3o Wtransnet. O Objectivo: ajudar as empresas do sector a encontrar novos colaboradores de confian\u00e7a para gerar novas &hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blog.wtransnet.com\/pt\/2-976-entrevistas-inter-profissionais-na-ii-edicao-de-madrid-connecta\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog Wtransnet Portugal\" \/>\n<meta property=\"article:published_time\" content=\"2012-03-20T00:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-02-03T16:57:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/blog.wtransnet.com\/pt\/wp-content\/uploads\/sites\/8\/2012\/03\/n12.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"150\" \/>\n\t<meta property=\"og:image:height\" content=\"150\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"wtransnet\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"wtransnet\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/blog.wtransnet.com\/pt\/2-976-entrevistas-inter-profissionais-na-ii-edicao-de-madrid-connecta\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/blog.wtransnet.com\/pt\/2-976-entrevistas-inter-profissionais-na-ii-edicao-de-madrid-connecta\/\"},\"author\":{\"name\":\"wtransnet\",\"@id\":\"https:\/\/blog.wtransnet.com\/pt\/#\/schema\/person\/fceb9548f80ce7f179d676f87807077c\"},\"headline\":\"2.976 Entrevistas inter-profissionais na II Edi\u00e7\u00e3o de Madrid Connecta\",\"datePublished\":\"2012-03-20T00:00:00+00:00\",\"dateModified\":\"2016-02-03T16:57:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/blog.wtransnet.com\/pt\/2-976-entrevistas-inter-profissionais-na-ii-edicao-de-madrid-connecta\/\"},\"wordCount\":157,\"commentCount\":0,\"image\":{\"@id\":\"https:\/\/blog.wtransnet.com\/pt\/2-976-entrevistas-inter-profissionais-na-ii-edicao-de-madrid-connecta\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/blog.wtransnet.com\/pt\/wp-content\/uploads\/sites\/8\/2012\/03\/n12.jpg\",\"articleSection\":[\"Funda\u00e7\u00e3o Wtransnet\",\"Transporte e atualidade\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/blog.wtransnet.com\/pt\/2-976-entrevistas-inter-profissionais-na-ii-edicao-de-madrid-connecta\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/blog.wtransnet.com\/pt\/2-976-entrevistas-inter-profissionais-na-ii-edicao-de-madrid-connecta\/\",\"url\":\"https:\/\/blog.wtransnet.com\/pt\/2-976-entrevistas-inter-profissionais-na-ii-edicao-de-madrid-connecta\/\",\"name\":\"2.976 Entrevistas inter-profissionais na II Edi\u00e7\u00e3o de Madrid Connecta - Blog Wtransnet Portugal\",\"isPartOf\":{\"@id\":\"https:\/\/blog.wtransnet.com\/pt\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/blog.wtransnet.com\/pt\/2-976-entrevistas-inter-profissionais-na-ii-edicao-de-madrid-connecta\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/blog.wtransnet.com\/pt\/2-976-entrevistas-inter-profissionais-na-ii-edicao-de-madrid-connecta\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/blog.wtransnet.com\/pt\/wp-content\/uploads\/sites\/8\/2012\/03\/n12.jpg\",\"datePublished\":\"2012-03-20T00:00:00+00:00\",\"dateModified\":\"2016-02-03T16:57:40+00:00\",\"author\":{\"@id\":\"https:\/\/blog.wtransnet.com\/pt\/#\/schema\/person\/fceb9548f80ce7f179d676f87807077c\"},\"breadcrumb\":{\"@id\":\"https:\/\/blog.wtransnet.com\/pt\/2-976-entrevistas-inter-profissionais-na-ii-edicao-de-madrid-connecta\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/blog.wtransnet.com\/pt\/2-976-entrevistas-inter-profissionais-na-ii-edicao-de-madrid-connecta\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/blog.wtransnet.com\/pt\/2-976-entrevistas-inter-profissionais-na-ii-edicao-de-madrid-connecta\/#primaryimage\",\"url\":\"https:\/\/blog.wtransnet.com\/pt\/wp-content\/uploads\/sites\/8\/2012\/03\/n12.jpg\",\"contentUrl\":\"https:\/\/blog.wtransnet.com\/pt\/wp-content\/uploads\/sites\/8\/2012\/03\/n12.jpg\",\"width\":150,\"height\":150},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/blog.wtransnet.com\/pt\/2-976-entrevistas-inter-profissionais-na-ii-edicao-de-madrid-connecta\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/blog.wtransnet.com\/pt\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"2.976 Entrevistas inter-profissionais na II Edi\u00e7\u00e3o de Madrid Connecta\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/blog.wtransnet.com\/pt\/#website\",\"url\":\"https:\/\/blog.wtransnet.com\/pt\/\",\"name\":\"Blog Wtransnet Portugal\",\"description\":\"Blog Wtransnet Portugal: Noticias do transporte, log\u00edstica e bolsa de cargas\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/blog.wtransnet.com\/pt\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/blog.wtransnet.com\/pt\/#\/schema\/person\/fceb9548f80ce7f179d676f87807077c\",\"name\":\"wtransnet\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/blog.wtransnet.com\/pt\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/a05fe32dee93b4aac2b3ec7f2963147f4949dc5f60df7d491cc2199728053e0b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/a05fe32dee93b4aac2b3ec7f2963147f4949dc5f60df7d491cc2199728053e0b?s=96&d=mm&r=g\",\"caption\":\"wtransnet\"},\"url\":\"https:\/\/blog.wtransnet.com\/pt\/author\/wtransnet\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"2.976 Entrevistas inter-profissionais na II Edi\u00e7\u00e3o de Madrid Connecta - Blog Wtransnet Portugal","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blog.wtransnet.com\/pt\/2-976-entrevistas-inter-profissionais-na-ii-edicao-de-madrid-connecta\/","og_locale":"es_ES","og_type":"article","og_title":"2.976 Entrevistas inter-profissionais na II Edi\u00e7\u00e3o de Madrid Connecta - Blog Wtransnet Portugal","og_description":"214 profissionais e 10 pa\u00edses europeus representados na maior jornada de Networking do sector 214 profissionais reuniram-se no passado 18 de Novembro em Madrid no II Encontro Internacional de Profissionais do Transporte de da Log\u00edstica organizado pela Funda\u00e7\u00e3o Wtransnet. O Objectivo: ajudar as empresas do sector a encontrar novos colaboradores de confian\u00e7a para gerar novas &hellip;","og_url":"https:\/\/blog.wtransnet.com\/pt\/2-976-entrevistas-inter-profissionais-na-ii-edicao-de-madrid-connecta\/","og_site_name":"Blog Wtransnet Portugal","article_published_time":"2012-03-20T00:00:00+00:00","article_modified_time":"2016-02-03T16:57:40+00:00","og_image":[{"width":150,"height":150,"url":"https:\/\/blog.wtransnet.com\/pt\/wp-content\/uploads\/sites\/8\/2012\/03\/n12.jpg","type":"image\/jpeg"}],"author":"wtransnet","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"wtransnet","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/blog.wtransnet.com\/pt\/2-976-entrevistas-inter-profissionais-na-ii-edicao-de-madrid-connecta\/#article","isPartOf":{"@id":"https:\/\/blog.wtransnet.com\/pt\/2-976-entrevistas-inter-profissionais-na-ii-edicao-de-madrid-connecta\/"},"author":{"name":"wtransnet","@id":"https:\/\/blog.wtransnet.com\/pt\/#\/schema\/person\/fceb9548f80ce7f179d676f87807077c"},"headline":"2.976 Entrevistas inter-profissionais na II Edi\u00e7\u00e3o de Madrid Connecta","datePublished":"2012-03-20T00:00:00+00:00","dateModified":"2016-02-03T16:57:40+00:00","mainEntityOfPage":{"@id":"https:\/\/blog.wtransnet.com\/pt\/2-976-entrevistas-inter-profissionais-na-ii-edicao-de-madrid-connecta\/"},"wordCount":157,"commentCount":0,"image":{"@id":"https:\/\/blog.wtransnet.com\/pt\/2-976-entrevistas-inter-profissionais-na-ii-edicao-de-madrid-connecta\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.wtransnet.com\/pt\/wp-content\/uploads\/sites\/8\/2012\/03\/n12.jpg","articleSection":["Funda\u00e7\u00e3o Wtransnet","Transporte e atualidade"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/blog.wtransnet.com\/pt\/2-976-entrevistas-inter-profissionais-na-ii-edicao-de-madrid-connecta\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/blog.wtransnet.com\/pt\/2-976-entrevistas-inter-profissionais-na-ii-edicao-de-madrid-connecta\/","url":"https:\/\/blog.wtransnet.com\/pt\/2-976-entrevistas-inter-profissionais-na-ii-edicao-de-madrid-connecta\/","name":"2.976 Entrevistas inter-profissionais na II Edi\u00e7\u00e3o de Madrid Connecta - Blog Wtransnet Portugal","isPartOf":{"@id":"https:\/\/blog.wtransnet.com\/pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/blog.wtransnet.com\/pt\/2-976-entrevistas-inter-profissionais-na-ii-edicao-de-madrid-connecta\/#primaryimage"},"image":{"@id":"https:\/\/blog.wtransnet.com\/pt\/2-976-entrevistas-inter-profissionais-na-ii-edicao-de-madrid-connecta\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.wtransnet.com\/pt\/wp-content\/uploads\/sites\/8\/2012\/03\/n12.jpg","datePublished":"2012-03-20T00:00:00+00:00","dateModified":"2016-02-03T16:57:40+00:00","author":{"@id":"https:\/\/blog.wtransnet.com\/pt\/#\/schema\/person\/fceb9548f80ce7f179d676f87807077c"},"breadcrumb":{"@id":"https:\/\/blog.wtransnet.com\/pt\/2-976-entrevistas-inter-profissionais-na-ii-edicao-de-madrid-connecta\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blog.wtransnet.com\/pt\/2-976-entrevistas-inter-profissionais-na-ii-edicao-de-madrid-connecta\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/blog.wtransnet.com\/pt\/2-976-entrevistas-inter-profissionais-na-ii-edicao-de-madrid-connecta\/#primaryimage","url":"https:\/\/blog.wtransnet.com\/pt\/wp-content\/uploads\/sites\/8\/2012\/03\/n12.jpg","contentUrl":"https:\/\/blog.wtransnet.com\/pt\/wp-content\/uploads\/sites\/8\/2012\/03\/n12.jpg","width":150,"height":150},{"@type":"BreadcrumbList","@id":"https:\/\/blog.wtransnet.com\/pt\/2-976-entrevistas-inter-profissionais-na-ii-edicao-de-madrid-connecta\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/blog.wtransnet.com\/pt\/"},{"@type":"ListItem","position":2,"name":"2.976 Entrevistas inter-profissionais na II Edi\u00e7\u00e3o de Madrid Connecta"}]},{"@type":"WebSite","@id":"https:\/\/blog.wtransnet.com\/pt\/#website","url":"https:\/\/blog.wtransnet.com\/pt\/","name":"Blog Wtransnet Portugal","description":"Blog Wtransnet Portugal: Noticias do transporte, log\u00edstica e bolsa de cargas","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blog.wtransnet.com\/pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/blog.wtransnet.com\/pt\/#\/schema\/person\/fceb9548f80ce7f179d676f87807077c","name":"wtransnet","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/blog.wtransnet.com\/pt\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/a05fe32dee93b4aac2b3ec7f2963147f4949dc5f60df7d491cc2199728053e0b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a05fe32dee93b4aac2b3ec7f2963147f4949dc5f60df7d491cc2199728053e0b?s=96&d=mm&r=g","caption":"wtransnet"},"url":"https:\/\/blog.wtransnet.com\/pt\/author\/wtransnet\/"}]}},"_links":{"self":[{"href":"https:\/\/blog.wtransnet.com\/pt\/wp-json\/wp\/v2\/posts\/12","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.wtransnet.com\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.wtransnet.com\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.wtransnet.com\/pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.wtransnet.com\/pt\/wp-json\/wp\/v2\/comments?post=12"}],"version-history":[{"count":0,"href":"https:\/\/blog.wtransnet.com\/pt\/wp-json\/wp\/v2\/posts\/12\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blog.wtransnet.com\/pt\/wp-json\/wp\/v2\/media\/146"}],"wp:attachment":[{"href":"https:\/\/blog.wtransnet.com\/pt\/wp-json\/wp\/v2\/media?parent=12"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.wtransnet.com\/pt\/wp-json\/wp\/v2\/categories?post=12"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.wtransnet.com\/pt\/wp-json\/wp\/v2\/tags?post=12"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}